{"id":1237,"date":"2017-09-25T09:39:11","date_gmt":"2017-09-25T14:39:11","guid":{"rendered":"http:\/\/prototipo.bienestar-total.com.mx\/contenido\/?p=1237"},"modified":"2018-01-11T12:30:07","modified_gmt":"2018-01-11T17:30:07","slug":"enfermedades-oculares","status":"publish","type":"post","link":"https:\/\/prototipo.bienestar-total.com.mx\/contenido\/enfermedades-oculares\/","title":{"rendered":"Enfermedades oculares"},"content":{"rendered":"<div class=\"art_titulo art_azulClaro\">Definici&oacute;n:<\/div>\n<div class=\"table-responsive\">\n<table class=\"table\">\n<tbody>\n<tr>\n<td>\n<p class=\"txt_nara\"><b>Cataratas<\/b><\/p>\n<p class=\"txt_nara\"><img loading=\"lazy\" decoding=\"async\" src=\"02_02_img\/s02-08-01.png\" width=\"100\" height=\"100\"><\/p>\n<\/td>\n<td><img decoding=\"async\" src=\"02_02_img\/flecha-naranja-1.png\"><\/td>\n<td>\n<div class=\"art_lista_simple art_azulClaro\">\n<ul>\n<li>Una catarata es la formaci&oacute;n de una opacidad       del cristalino normalmente claro del ojo.<\/li>\n<li>Se puede desarrollar en uno o ambos ojos. <\/li>\n<li>La opacidad del cristalino hace que la visi&oacute;n       sea borrosa. Cierto grado de formaci&oacute;n de cataratas es normal con el       envejecimiento, pero ciertas exposiciones o condiciones pueden acelerar el       proceso. <\/li>\n<li>El tabaquismo tambi&eacute;n puede aumentar su riesgo       de cataratas.<\/li>\n<li>Si una catarata interfiere con sus actividades       diarias, su cristalino opaco puede extirparse quir&uacute;rgicamente y       reemplazarse con un implante de un cristalino de pl&aacute;stico. <\/li>\n<\/ul>\n<\/div>\n<p><span class=\"txt_nara\"><b>Precauci&oacute;n: <\/b><\/span>Reduce el resplandor, evita o retrasa  las cataratas mediante el uso de anteojos para sol que bloqueen la luz UV  cuando te expongas al sol brillante. Aseg&uacute;rate de contar con la iluminaci&oacute;n  adecuada.<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<tbody>\n<tr>\n<td>\n<p class=\"txt_nara\"><b>Glaucoma<\/b><\/p>\n<p class=\"txt_nara\"><img loading=\"lazy\" decoding=\"async\" src=\"02_02_img\/s02-08-02.png\" width=\"100\" height=\"100\"><\/p>\n<\/td>\n<td><img decoding=\"async\" src=\"02_02_img\/flecha-naranja-1.png\"><\/td>\n<td>\n<div class=\"art_lista_simple art_azulClaro\">\n<ul>\n<li>El glaucoma implica da&ntilde;o en el nervio ocular       (&oacute;ptico) ocasionado por intolerancia a la presi&oacute;n dentro del globo ocular. <\/li>\n<li>La presi&oacute;n aumenta cuando se bloquean los       peque&ntilde;os poros que por lo regular permiten que el l&iacute;quido drene del       interior de su ojo. <\/li>\n<li>El da&ntilde;o en el nervio &oacute;ptico hace que tu visi&oacute;n       lateral disminuya de manera gradual. Si no se trata, el glaucoma puede       conducir a ceguera. <\/li>\n<\/ul>\n<\/div>\n<p><span class=\"txt_nara\"><b>Precauci&oacute;n:<\/b><\/span>Dado que los s&iacute;ntomas in&iacute;ciales pueden ser  sutiles, es importante someterse a ex&aacute;menes oculares regulares. Si se  diagnostica y trata de manera oportuna, el glaucoma cr&oacute;nico puede controlarse  con gotas oculares, medicamentos orales o cirug&iacute;a. Si tienes s&iacute;ntomas como  dolor de cabeza grave, dolor en el ojo o la frente, n&aacute;usea, visi&oacute;n borrosa o  arco iris alrededor de las luces por la noche, busca evaluaci&oacute;n inmediata. El  tratamiento puede requerir cirug&iacute;a l&aacute;ser de emergencia.<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<tbody>\n<tr>\n<td>\n<p class=\"txt_nara\"><b>Degeneraci&oacute;n macular<\/b><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"02_02_img\/s02-08-03.png\" width=\"100\" height=\"100\"><\/p>\n<\/td>\n<td><img decoding=\"async\" src=\"02_02_img\/flecha-naranja-1.png\"><\/td>\n<td>\n<div class=\"art_lista_simple art_azulClaro\">\n<ul>\n<li>La  degeneraci&oacute;n macular (seca y h&uacute;meda) causa visi&oacute;n central borrosa o un punto  ciego en el centro de la visi&oacute;n. No afecta la visi&oacute;n lateral y por lo regular  no lleva a la ceguera total.<\/li>\n<li>El padecimiento ocurre cuando el tejido del       centro de la retina (m&aacute;cula) se deteriora. <\/li>\n<\/ul><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<tbody>\n        <\/tbody>\n<tbody>\n        <\/tbody>\n<tbody>\n        <\/tbody>\n<\/table>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Definici&oacute;n: Cataratas Una catarata es la formaci&oacute;n de una opacidad del cristalino normalmente claro del ojo. Se puede desarrollar en uno o ambos ojos. La opacidad del cristalino hace que la visi&oacute;n sea borrosa. Cierto grado de formaci&oacute;n de cataratas es normal con el envejecimiento, pero ciertas exposiciones o condiciones pueden acelerar el proceso. El &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/prototipo.bienestar-total.com.mx\/contenido\/enfermedades-oculares\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abEnfermedades oculares\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[108],"tags":[],"class_list":["post-1237","post","type-post","status-publish","format-standard","hentry","category-ojos-y-vision"],"campos_v1":[],"_links":{"self":[{"href":"https:\/\/prototipo.bienestar-total.com.mx\/contenido\/wp-json\/wp\/v2\/posts\/1237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prototipo.bienestar-total.com.mx\/contenido\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prototipo.bienestar-total.com.mx\/contenido\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prototipo.bienestar-total.com.mx\/contenido\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prototipo.bienestar-total.com.mx\/contenido\/wp-json\/wp\/v2\/comments?post=1237"}],"version-history":[{"count":2,"href":"https:\/\/prototipo.bienestar-total.com.mx\/contenido\/wp-json\/wp\/v2\/posts\/1237\/revisions"}],"predecessor-version":[{"id":2219,"href":"https:\/\/prototipo.bienestar-total.com.mx\/contenido\/wp-json\/wp\/v2\/posts\/1237\/revisions\/2219"}],"wp:attachment":[{"href":"https:\/\/prototipo.bienestar-total.com.mx\/contenido\/wp-json\/wp\/v2\/media?parent=1237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prototipo.bienestar-total.com.mx\/contenido\/wp-json\/wp\/v2\/categories?post=1237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prototipo.bienestar-total.com.mx\/contenido\/wp-json\/wp\/v2\/tags?post=1237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}