{"id":864,"date":"2017-09-07T13:05:09","date_gmt":"2017-09-07T18:05:09","guid":{"rendered":"http:\/\/prototipo.bienestar-total.com.mx\/contenido\/?p=864"},"modified":"2019-05-14T10:54:54","modified_gmt":"2019-05-14T15:54:54","slug":"medicamentos-3","status":"publish","type":"post","link":"https:\/\/prototipo.bienestar-total.com.mx\/contenido\/medicamentos-3\/","title":{"rendered":"Medicamentos"},"content":{"rendered":"<div class=\"art_titulo txt_nara\">\n<p><span>Medicamentos<\/span><\/p>\n<\/p><\/div>\n<div class=\"art_txtimg_izq\">\n    <img loading=\"lazy\" decoding=\"async\" src=\"img\/img_04_30.png\" alt=\"\" width=\"166\" height=\"147\" ><\/p>\n<div>\n<p>&nbsp;<\/p>\n<p>Los medicamentos de prescripci&oacute;n para bajar de peso son apropiados para personas con sobrepeso y obesidad moderados, que tienen complicaciones de salud relacionadas con el peso.<\/p><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<div class=\"art_lista_simple naranja\">\n<ul>\n<li>Si est&aacute;s entre quienes pueden beneficiarse a partir de los medicamentos para perder peso, probablemente necesitar&aacute;s tomarlos por tiempo indefinido. Muchos estudios muestran que cuando se suspende ese tipo de tratamiento, se recupera gran parte del peso excesivo, o todo.<\/li>\n<\/ul>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Medicamentos &nbsp; Los medicamentos de prescripci&oacute;n para bajar de peso son apropiados para personas con sobrepeso y obesidad moderados, que tienen complicaciones de salud relacionadas con el peso. &nbsp; Si est&aacute;s entre quienes pueden beneficiarse a partir de los medicamentos para perder peso, probablemente necesitar&aacute;s tomarlos por tiempo indefinido. Muchos estudios muestran que cuando se &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/prototipo.bienestar-total.com.mx\/contenido\/medicamentos-3\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00abMedicamentos\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":2043,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68],"tags":[],"class_list":["post-864","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cuando-necesitas-mas-ayuda"],"campos_v1":[],"_links":{"self":[{"href":"https:\/\/prototipo.bienestar-total.com.mx\/contenido\/wp-json\/wp\/v2\/posts\/864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prototipo.bienestar-total.com.mx\/contenido\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/prototipo.bienestar-total.com.mx\/contenido\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/prototipo.bienestar-total.com.mx\/contenido\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/prototipo.bienestar-total.com.mx\/contenido\/wp-json\/wp\/v2\/comments?post=864"}],"version-history":[{"count":1,"href":"https:\/\/prototipo.bienestar-total.com.mx\/contenido\/wp-json\/wp\/v2\/posts\/864\/revisions"}],"predecessor-version":[{"id":865,"href":"https:\/\/prototipo.bienestar-total.com.mx\/contenido\/wp-json\/wp\/v2\/posts\/864\/revisions\/865"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prototipo.bienestar-total.com.mx\/contenido\/wp-json\/wp\/v2\/media\/2043"}],"wp:attachment":[{"href":"https:\/\/prototipo.bienestar-total.com.mx\/contenido\/wp-json\/wp\/v2\/media?parent=864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/prototipo.bienestar-total.com.mx\/contenido\/wp-json\/wp\/v2\/categories?post=864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/prototipo.bienestar-total.com.mx\/contenido\/wp-json\/wp\/v2\/tags?post=864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}